{"id":7352,"date":"2022-07-19T15:48:08","date_gmt":"2022-07-19T13:48:08","guid":{"rendered":"https:\/\/www.ffpjp69.com\/?p=7352"},"modified":"2023-04-11T13:03:35","modified_gmt":"2023-04-11T11:03:35","slug":"un-double-pour-les-championnes-de-france","status":"publish","type":"post","link":"https:\/\/www.ffpjp69.com\/index.php\/2022\/07\/19\/un-double-pour-les-championnes-de-france\/","title":{"rendered":"Un doubl\u00e9 pour les championnes de France"},"content":{"rendered":"\n<p class=\"has-text-align-center\">Samedi 16 et Dimanche 17, a eu lieu la 20e \u00e9dition du championnat de France cat\u00e9gorie triplette f\u00e9minin \u00e0 Chalon sur Sa\u00f4ne (71). Pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive, le Rh\u00f4ne \u00e0 brillamment remport\u00e9 cette comp\u00e9tition.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Le trio Charlotte DARODES, Mouna BEJI et Ludivine D&rsquo;ISIDORO Ram\u00e8nent la coupe \u00e0 la maison et ont fi\u00e8rement repr\u00e9sent\u00e9 le Rh\u00f4ne.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Il s&rsquo;agit de leur deuxi\u00e8me victoire apr\u00e8s leur succ\u00e8s en 2021 \u00e0 Palavas-les-Flots ce qui leur permet donc en une comp\u00e9tition de conserver leur titre et de s&rsquo;offrir un doubl\u00e9. Comme en 2021, Jean-Louis BERETTA \u00e9tait l&rsquo;heureux d\u00e9l\u00e9gu\u00e9 des gagnantes.<\/p>\n\n\n\n<p class=\"has-text-align-center\">La finale s&rsquo;est d\u00e9roul\u00e9e entre le Rh\u00f4ne (69) et la Martinique (972) compos\u00e9e de DECAS Th\u00e9ophanie, PIERRE-MICHEL Daniel et SOMMIER Mirella que nous f\u00e9licitons pour leur titre de vice-championne de France.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Nous tenons \u00e0 remercier le Comit\u00e9 de Sa\u00f4ne-et-Loire et la F\u00e9d\u00e9ration Fran\u00e7aise de P\u00e9tanque et Jeu Proven\u00e7al pour l&rsquo;organisation de ce championnat de France qui fut une r\u00e9ussite.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Un grand bravo au club de Lyon CANUTS, le club des trois championnes.<\/p>\n\n\n\n<p class=\"has-text-align-center\">D\u00e9couvrez quelques images de la comp\u00e9tition (source des photos : page Facebook \u00ab\u00a0Lyon Canuts\u00a0\u00bb).<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1069\" data-id=\"7353\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293809041_5508427639178282_7651609705149166474_n.jpg\" alt=\"\" class=\"wp-image-7353\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293809041_5508427639178282_7651609705149166474_n.jpg 1600w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293809041_5508427639178282_7651609705149166474_n-300x200.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293809041_5508427639178282_7651609705149166474_n-1024x684.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293809041_5508427639178282_7651609705149166474_n-768x513.jpg 768w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293809041_5508427639178282_7651609705149166474_n-1536x1026.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1069\" data-id=\"7354\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293595677_5508427112511668_4993077557764142126_n.jpg\" alt=\"\" class=\"wp-image-7354\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293595677_5508427112511668_4993077557764142126_n.jpg 1600w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293595677_5508427112511668_4993077557764142126_n-300x200.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293595677_5508427112511668_4993077557764142126_n-1024x684.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293595677_5508427112511668_4993077557764142126_n-768x513.jpg 768w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293595677_5508427112511668_4993077557764142126_n-1536x1026.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1069\" data-id=\"7355\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293662204_5508426952511684_4365713305327519723_n.jpg\" alt=\"\" class=\"wp-image-7355\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293662204_5508426952511684_4365713305327519723_n.jpg 1600w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293662204_5508426952511684_4365713305327519723_n-300x200.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293662204_5508426952511684_4365713305327519723_n-1024x684.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293662204_5508426952511684_4365713305327519723_n-768x513.jpg 768w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293662204_5508426952511684_4365713305327519723_n-1536x1026.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1069\" data-id=\"7356\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293848283_5508424719178574_6615291073144326203_n.jpg\" alt=\"\" class=\"wp-image-7356\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293848283_5508424719178574_6615291073144326203_n.jpg 1600w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293848283_5508424719178574_6615291073144326203_n-300x200.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293848283_5508424719178574_6615291073144326203_n-1024x684.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293848283_5508424719178574_6615291073144326203_n-768x513.jpg 768w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293848283_5508424719178574_6615291073144326203_n-1536x1026.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1452\" height=\"1068\" data-id=\"7357\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293652317_5508423595845353_394771596603351888_n.jpg\" alt=\"\" class=\"wp-image-7357\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293652317_5508423595845353_394771596603351888_n.jpg 1452w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293652317_5508423595845353_394771596603351888_n-300x221.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293652317_5508423595845353_394771596603351888_n-1024x753.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293652317_5508423595845353_394771596603351888_n-768x565.jpg 768w\" sizes=\"auto, (max-width: 1452px) 100vw, 1452px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1483\" height=\"1062\" data-id=\"7358\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293577219_5508409015846811_6226795440336601108_n.jpg\" alt=\"\" class=\"wp-image-7358\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293577219_5508409015846811_6226795440336601108_n.jpg 1483w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293577219_5508409015846811_6226795440336601108_n-300x215.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293577219_5508409015846811_6226795440336601108_n-1024x733.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293577219_5508409015846811_6226795440336601108_n-768x550.jpg 768w\" sizes=\"auto, (max-width: 1483px) 100vw, 1483px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" data-id=\"7360\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/294430096_178564627964839_5379758274373891233_n.jpg\" alt=\"\" class=\"wp-image-7360\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/294430096_178564627964839_5379758274373891233_n.jpg 1080w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/294430096_178564627964839_5379758274373891233_n-300x169.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/294430096_178564627964839_5379758274373891233_n-1024x576.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/294430096_178564627964839_5379758274373891233_n-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"638\" data-id=\"7374\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293808440_5508404949180551_6617373607653912406_n-1.jpg\" alt=\"\" class=\"wp-image-7374\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293808440_5508404949180551_6617373607653912406_n-1.jpg 960w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293808440_5508404949180551_6617373607653912406_n-1-300x199.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293808440_5508404949180551_6617373607653912406_n-1-768x510.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-element-caption\">Championnes<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"764\" data-id=\"7375\" src=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293777881_5508427795844933_8747597207304699832_n-1-1024x764.jpg\" alt=\"\" class=\"wp-image-7375\" srcset=\"https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293777881_5508427795844933_8747597207304699832_n-1-1024x764.jpg 1024w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293777881_5508427795844933_8747597207304699832_n-1-300x224.jpg 300w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293777881_5508427795844933_8747597207304699832_n-1-768x573.jpg 768w, https:\/\/www.ffpjp69.com\/wp-content\/uploads\/2022\/07\/293777881_5508427795844933_8747597207304699832_n-1.jpg 1424w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Vice-championnes<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Samedi 16 et Dimanche 17, a eu lieu la 20e \u00e9dition du championnat de France&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148],"tags":[],"class_list":["post-7352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultat"],"_links":{"self":[{"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/posts\/7352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/comments?post=7352"}],"version-history":[{"count":13,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/posts\/7352\/revisions"}],"predecessor-version":[{"id":10670,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/posts\/7352\/revisions\/10670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/media\/7359"}],"wp:attachment":[{"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/media?parent=7352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/categories?post=7352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ffpjp69.com\/index.php\/wp-json\/wp\/v2\/tags?post=7352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}